{"id":8249,"date":"2020-11-04T18:36:10","date_gmt":"2020-11-04T18:36:10","guid":{"rendered":"https:\/\/deltafm.com.uy\/sitio\/?p=8249"},"modified":"2020-11-04T18:36:10","modified_gmt":"2020-11-04T18:36:10","slug":"policia-de-lavalleja-investiga-una-estafa-a-una-persona-de-94-anos","status":"publish","type":"post","link":"https:\/\/deltafm.com.uy\/sitio\/2020\/11\/04\/policia-de-lavalleja-investiga-una-estafa-a-una-persona-de-94-anos\/","title":{"rendered":"Polic\u00eda de Lavalleja investiga una estafa a una persona de 94 a\u00f1os"},"content":{"rendered":"<h3>A Direcci\u00f3n Departamental de Investigaciones fueron derivadas las actuaciones para identificar a quienes est\u00e1n detr\u00e1s de una estafa cometida en perjuicio de una ciudadana de noventa y cuatro a\u00f1os.<\/h3>\n<h3>En esta ocasi\u00f3n la damnificada recibi\u00f3 una llamada a su tel\u00e9fono fijo y con la voz ronca un hombre que se hizo pasar por su sobrino le manifest\u00f3 que si ten\u00eda dinero en el Banco lo deb\u00eda cambiar porque hab\u00edan billetes nuevos, manifest\u00e1ndole esta que el dinero lo ten\u00eda en su casa. El hombre le indic\u00f3 que iba a pasar la Gerente del Banco por su casa a levantar el dinero.<\/h3>\n<h3>Posteriormente se present\u00f3 en su domicilio una mujer, a quien le entreg\u00f3 la suma de cien mil pesos uruguayos y su c\u00e9dula de identidad en una bolsa de nylon.<\/h3>\n<h3>Esta situaci\u00f3n pone nuevamente en alerta a las autoridades, por lo que se orienta a no brindar informaci\u00f3n personal a desconocidos, previendo que en muchas ocasiones quienes est\u00e1n detr\u00e1s de estas maniobras comienzan el di\u00e1logo intentando entrar en confianza con la v\u00edctima, ofreciendo productos, servicios o pr\u00e9stamos, con el prop\u00f3sito de acceder a sus datos y una vez que hacen esto pueden volver a llamar.<\/h3>\n<h3>Por otra parte se recuerda que en caso de tener v\u00ednculo con alguna entidad financiera, estas cuentan con sus propios canales de comunicaci\u00f3n para contactarlo de manera exclusiva y no por terceras personas. Teniendo en cuenta que no existe ning\u00fan mecanismo ni orden alguna para el cambio de billetes nacionales o extranjeros de manera obligatoria.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>A Direcci\u00f3n Departamental de Investigaciones fueron derivadas las actuaciones para identificar a quienes est\u00e1n detr\u00e1s de una estafa cometida en perjuicio de una ciudadana de noventa y cuatro a\u00f1os. En esta ocasi\u00f3n la damnificada recibi\u00f3 una llamada a su tel\u00e9fono fijo y con la voz ronca un hombre que se hizo pasar por su sobrino&#8230;<\/p>\n<p><a rel=\"bookmark\" class=\"decibel-button-text wvc-button wvc-button-size-sm wolf-core-button wolf-core-button-size-sm\" href=\"https:\/\/deltafm.com.uy\/sitio\/2020\/11\/04\/policia-de-lavalleja-investiga-una-estafa-a-una-persona-de-94-anos\/\"><small class=\"wvc-button-background-fill wolf-core-button-background-fill\"><\/small><span>seguir leyendo<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":8250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[17],"tags":[],"class_list":["post-8249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","entry-post-skin-dark","entry","clearfix","entry-post-module-layout-sidebar-right","thumbnail-color-tone-dark","entry-post","entry-standard","entry-post-standard"],"_links":{"self":[{"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/posts\/8249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/comments?post=8249"}],"version-history":[{"count":1,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/posts\/8249\/revisions"}],"predecessor-version":[{"id":8251,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/posts\/8249\/revisions\/8251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/media\/8250"}],"wp:attachment":[{"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/media?parent=8249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/categories?post=8249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deltafm.com.uy\/sitio\/wp-json\/wp\/v2\/tags?post=8249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}